
{"id":2099,"date":"2016-10-04T09:03:32","date_gmt":"2016-10-04T09:03:32","guid":{"rendered":"http:\/\/blog.baque.com\/?p=356"},"modified":"2018-03-21T12:48:01","modified_gmt":"2018-03-21T12:48:01","slug":"beneficios-del-cafe-para-la-salud","status":"publish","type":"post","link":"https:\/\/www.baque.com\/es\/blog\/beneficios-del-cafe-para-la-salud\/","title":{"rendered":"Beneficios del caf\u00e9 para la salud"},"content":{"rendered":"<p class='entradilla'>En nuestra cultura el caf\u00e9 es mucho m\u00e1s que una bebida, es una forma de vida. Protagoniza muchos momentos importantes a lo largo del d\u00eda.<\/p>\n<p>Amaneces con \u00e9l, quedas para hablar con alguien al sorbo de un buen caf\u00e9 o rematas una fant\u00e1stica comida haciendo sobremesa con una estimulante taza. Puede que \u00e9sta sea la mayor ventaja de su consumo: <strong>tomarlo une<\/strong>. Pero lo cierto es que en los \u00faltimos a\u00f1os cada vez son m\u00e1s los estudios cient\u00edficos que revelan los <strong>beneficios del caf\u00e9 para la salud<\/strong>.<\/p>\n<p>El <a href=\"http:\/\/www.baque.com\/es\/cafes-baque\/nosotros\/decalogo-buen-cafetero\" target=\"_blank\" rel=\"noopener\">consumo de caf\u00e9 con moderaci\u00f3n<\/a> <strong>repercute positivamente en nuestra salud<\/strong>; no hay que perder de vista que en s\u00ed es de origen natural y tiene dos componentes tan importantes para nuestro bienestar, como la <strong>cafe\u00edna<\/strong> y los <strong>antioxidantes<\/strong>.<\/p>\n<p>De hecho, parece que a medida que avanzan las investigaciones aumentan sus ventajas, as\u00ed que veamos cu\u00e1les son los <strong>beneficios del caf\u00e9 cient\u00edficamente demostrados<\/strong>.<\/p>\n<h2>Los 5 principales beneficios del caf\u00e9<\/h2>\n<h3>1. Contiene nutrientes esenciales.<\/h3>\n<p>Lo primero de todo, una taza contiene vitaminas B2 y B5, magnesio, potasio y niacina. Y adem\u00e1s, es la mayor fuente de antioxidantes, m\u00e1s que la fruta o los vegetales.<\/p>\n<h3>2. Mejora aspectos de la funci\u00f3n cerebral.<\/h3>\n<p>La cafe\u00edna es el psicoactivo m\u00e1s consumido del mundo y el activo m\u00e1s importante de esta bebida.<\/p>\n<p>Nada m\u00e1s consumirlo act\u00faa en el cerebro, aumentando sustancias como la dopamina o la norepinefrina y que aceleran la actividad cerebral. Esto, por ejemplo,\u00a0<strong>favorece la concentraci\u00f3n<\/strong>, la memoria, el \u00e1nimo, los niveles de energ\u00eda, los tiempos de reacci\u00f3n o la funci\u00f3n cognitiva en general.<\/p>\n<h3>3. Ayuda a quemar grasas.<\/h3>\n<p>La cafe\u00edna est\u00e1 presente en la mayor\u00eda de los suplementos alimenticios que ayudan a adelgazar. Es una de las pocas sustancias naturales que favorece la quema de grasas. \u00a1Ojo! El consumo excesivo reduce este efecto.<\/p>\n<h3>4. Mejora el rendimiento f\u00edsico.<\/h3>\n<p>Otra de las <strong>ventajas de la cafe\u00edna <\/strong>es que aumenta los niveles de adrenalina. Lo que se traduce en que las c\u00e9lulas grasas descomponen la grasa corporal y la liberan como \u00e1cidos grasos libres, lo que usamos como combustible cuando hacemos ejercicio.<\/p>\n<p>Este es uno de los principales motivos que explica <a href=\"http:\/\/www.cicas.es\/noticias\/el-cafe-vuelve-a-ser-el-protagonista-en-un-partido-de-tenis-entre-wawrinka-y-nadal\" target=\"_blank\" rel=\"noopener\"><strong>por qu\u00e9 los deportistas toman caf\u00e9 <\/strong><\/a>antes de competir.<\/p>\n<h3>5. Previene enfermedades.<\/h3>\n<p>Otro de sus principales beneficios es que repercute directamente sobre la prevenci\u00f3n de enfermedades y patolog\u00edas. <strong>El caf\u00e9 reduce el riesgo de padecer enfermedades<\/strong> como:<\/p>\n<p><u>La diabetes<\/u>.<\/p>\n<p>Diversos estudios revelan que <strong>la gente que consume caf\u00e9 tiene menos riesgo de padecer diabetes<\/strong>. Algunos incluso se atreven a dar cifras: hasta un 67% menos de posibilidades de tener esta enfermedad.<\/p>\n<p><u>Enfermedades neurodegenerativas<\/u>.<\/p>\n<p>Pese al progresivo envejecimiento de la poblaci\u00f3n, enfermedades como el P\u00e1rkinson o el Alzh\u00e9imer a\u00fan no tienen cura. Sin embargo, parece que gracias a la cafe\u00edna hay un 65% menos de probabilidades de tener Alzh\u00e9imer y hasta un 60% de sufrir P\u00e1rkinson. De hecho, el consumo de caf\u00e9 descafeinado no ha mostrado ninguna de estas dos ventajas.<\/p>\n<p><u>Cirrosis<\/u>.<\/p>\n<p>Otros estudios concluyen que quien bebe m\u00e1s de 4 de caf\u00e9s al d\u00eda tiene un <strong>80% menos de posibilidades de padecer Cirrosis<\/strong>. Aunque claro, ese no es el consumo recomendado.<\/p>\n<p><u>Depresi\u00f3n<\/u>.<\/p>\n<p>Tomar entre<strong> 2 y 4 tazas de caf\u00e9 al d\u00eda<\/strong> reduce tambi\u00e9n el riesgo de padecer depresi\u00f3n, sobre todo en mujeres. Investigaciones realizadas por la Universidad de Harvard aseguran que incluso reduce la posibilidad de suicidio en hasta un 50% menos de probabilidades.<\/p>\n<p><u>Infarto<\/u>.<\/p>\n<p>Y aqu\u00ed la gran paradoja. Aunque es bien sabido que la cafe\u00edna aumenta la presi\u00f3n sangu\u00ednea, reduce el riesgo de desarrollar una enfermedad cardiovascular e incluso previene la posibilidad de infarto.<\/p>\n<p><u>Ciertos tipos de c\u00e1ncer<\/u>.<\/p>\n<p>Por \u00faltimo los beneficios del caf\u00e9 contra el c\u00e1ncer. Est\u00e1 demostrado que el caf\u00e9 reduce el riesgo de prevenir diferentes tipos de c\u00e1ncer, como el de col\u00f3n, mama o pr\u00f3stata, entre otros.<\/p>\n<p>En definitiva, son muchos y variados los <strong>beneficios del caf\u00e9 para la salud<\/strong>. No obstante, recuerda que su consumo debe ser moderado. Nada en exceso es bueno. Por eso te recomendamos <strong>no tomar m\u00e1s de 4-5 tazas<\/strong> al d\u00eda.<\/p>\n<h4>Queremos que sigas disfrutando de tu \u201cmomento caf\u00e9\u201d.<\/h4>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.baque.com\/es\/para-casa\/cafe\/capsulas-organicas\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2284 size-full\" src=\"http:\/\/www.baque.com\/wp-content\/uploads\/2018\/01\/CTA-escuela-cafe.jpg\" alt=\"CTA escuela de caf\u00e9\" width=\"1150\" height=\"350\" srcset=\"https:\/\/www.baque.com\/wp-content\/uploads\/2018\/01\/CTA-escuela-cafe.jpg 1150w, https:\/\/www.baque.com\/wp-content\/uploads\/2018\/01\/CTA-escuela-cafe-331x101.jpg 331w, https:\/\/www.baque.com\/wp-content\/uploads\/2018\/01\/CTA-escuela-cafe-768x234.jpg 768w\" sizes=\"auto, (max-width: 1150px) 100vw, 1150px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En nuestra cultura el caf\u00e9 es mucho m\u00e1s que una bebida, es una forma de vida. Protagoniza muchos momentos importantes a lo largo del d\u00eda. <\/p>\n","protected":false},"author":1,"featured_media":2428,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[34],"tags":[22,27,30],"class_list":["post-2099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nos-gusta-el-cafe","tag-cafe-para-despertar","tag-historia-del-cafe","tag-preparar-cafe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Beneficios del caf\u00e9 para la salud | Blog de Caf\u00e9s Baqu\u00e9<\/title>\n<meta name=\"description\" content=\"Conoce algunos de los beneficios que aporta el caf\u00e9 al cuerpo humano. Ayuda a prevenir enfermedades y es fuente de energ\u00eda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beneficios del caf\u00e9 para la salud | Blog de Caf\u00e9s Baqu\u00e9\" \/>\n<meta property=\"og:description\" content=\"Conoce algunos de los beneficios que aporta el caf\u00e9 al cuerpo humano. Ayuda a prevenir enfermedades y es fuente de energ\u00eda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.baque.com\/es\/blog\/beneficios-del-cafe-para-la-salud\/\" \/>\n<meta property=\"og:site_name\" content=\"Caf\u00e9s Baqu\u00e9\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-04T09:03:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-21T12:48:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.baque.com\/wp-content\/uploads\/2016\/10\/beneficios-del-cafe-para-la-salud.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"655\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"baque\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"baque\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/beneficios-del-cafe-para-la-salud\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/beneficios-del-cafe-para-la-salud\\\/\"},\"author\":{\"name\":\"baque\",\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/#\\\/schema\\\/person\\\/32c8c583e6573818274e39ba0178ea0c\"},\"headline\":\"Beneficios del caf\u00e9 para la salud\",\"datePublished\":\"2016-10-04T09:03:32+00:00\",\"dateModified\":\"2018-03-21T12:48:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/beneficios-del-cafe-para-la-salud\\\/\"},\"wordCount\":723,\"commentCount\":5,\"image\":{\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/beneficios-del-cafe-para-la-salud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.baque.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/beneficios-del-cafe-para-la-salud.jpg\",\"keywords\":[\"caf\u00e9 para despertar\",\"historia del caf\u00e9\",\"preparar caf\u00e9\"],\"articleSection\":[\"Nos gusta el caf\u00e9\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/beneficios-del-cafe-para-la-salud\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/beneficios-del-cafe-para-la-salud\\\/\",\"url\":\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/beneficios-del-cafe-para-la-salud\\\/\",\"name\":\"Beneficios del caf\u00e9 para la salud | Blog de Caf\u00e9s Baqu\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/beneficios-del-cafe-para-la-salud\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/beneficios-del-cafe-para-la-salud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.baque.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/beneficios-del-cafe-para-la-salud.jpg\",\"datePublished\":\"2016-10-04T09:03:32+00:00\",\"dateModified\":\"2018-03-21T12:48:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/#\\\/schema\\\/person\\\/32c8c583e6573818274e39ba0178ea0c\"},\"description\":\"Conoce algunos de los beneficios que aporta el caf\u00e9 al cuerpo humano. Ayuda a prevenir enfermedades y es fuente de energ\u00eda.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/beneficios-del-cafe-para-la-salud\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/beneficios-del-cafe-para-la-salud\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/beneficios-del-cafe-para-la-salud\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.baque.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/beneficios-del-cafe-para-la-salud.jpg\",\"contentUrl\":\"https:\\\/\\\/www.baque.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/beneficios-del-cafe-para-la-salud.jpg\",\"width\":1300,\"height\":655},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/beneficios-del-cafe-para-la-salud\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.baque.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Beneficios del caf\u00e9 para la salud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.baque.com\\\/es\\\/\",\"name\":\"Caf\u00e9s Baqu\u00e9\",\"description\":\"Somos l\u00edderes en hosteler\u00eda en Pa\u00eds Vasco y La Rioja y una de las marcas m\u00e1s reconocidas en el mercado nacional. Somos una empresa familiar en constante innovaci\u00f3n en el producto. Tostamos y distribuimos caf\u00e9 molido, en grano y c\u00e1psulas para disfrutar en casa, en el bar y en la oficina.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.baque.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/#\\\/schema\\\/person\\\/32c8c583e6573818274e39ba0178ea0c\",\"name\":\"baque\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e662fd223ca8a44ab1e60e541b95b68e1a42729b8396361e1232af01ddb23e51?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e662fd223ca8a44ab1e60e541b95b68e1a42729b8396361e1232af01ddb23e51?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e662fd223ca8a44ab1e60e541b95b68e1a42729b8396361e1232af01ddb23e51?s=96&d=mm&r=g\",\"caption\":\"baque\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Beneficios del caf\u00e9 para la salud | Blog de Caf\u00e9s Baqu\u00e9","description":"Conoce algunos de los beneficios que aporta el caf\u00e9 al cuerpo humano. Ayuda a prevenir enfermedades y es fuente de energ\u00eda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Beneficios del caf\u00e9 para la salud | Blog de Caf\u00e9s Baqu\u00e9","og_description":"Conoce algunos de los beneficios que aporta el caf\u00e9 al cuerpo humano. Ayuda a prevenir enfermedades y es fuente de energ\u00eda.","og_url":"https:\/\/www.baque.com\/es\/blog\/beneficios-del-cafe-para-la-salud\/","og_site_name":"Caf\u00e9s Baqu\u00e9","article_published_time":"2016-10-04T09:03:32+00:00","article_modified_time":"2018-03-21T12:48:01+00:00","og_image":[{"width":1300,"height":655,"url":"https:\/\/www.baque.com\/wp-content\/uploads\/2016\/10\/beneficios-del-cafe-para-la-salud.jpg","type":"image\/jpeg"}],"author":"baque","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"baque","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.baque.com\/es\/blog\/beneficios-del-cafe-para-la-salud\/#article","isPartOf":{"@id":"https:\/\/www.baque.com\/es\/blog\/beneficios-del-cafe-para-la-salud\/"},"author":{"name":"baque","@id":"https:\/\/www.baque.com\/es\/#\/schema\/person\/32c8c583e6573818274e39ba0178ea0c"},"headline":"Beneficios del caf\u00e9 para la salud","datePublished":"2016-10-04T09:03:32+00:00","dateModified":"2018-03-21T12:48:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.baque.com\/es\/blog\/beneficios-del-cafe-para-la-salud\/"},"wordCount":723,"commentCount":5,"image":{"@id":"https:\/\/www.baque.com\/es\/blog\/beneficios-del-cafe-para-la-salud\/#primaryimage"},"thumbnailUrl":"https:\/\/www.baque.com\/wp-content\/uploads\/2016\/10\/beneficios-del-cafe-para-la-salud.jpg","keywords":["caf\u00e9 para despertar","historia del caf\u00e9","preparar caf\u00e9"],"articleSection":["Nos gusta el caf\u00e9"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.baque.com\/es\/blog\/beneficios-del-cafe-para-la-salud\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.baque.com\/es\/blog\/beneficios-del-cafe-para-la-salud\/","url":"https:\/\/www.baque.com\/es\/blog\/beneficios-del-cafe-para-la-salud\/","name":"Beneficios del caf\u00e9 para la salud | Blog de Caf\u00e9s Baqu\u00e9","isPartOf":{"@id":"https:\/\/www.baque.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.baque.com\/es\/blog\/beneficios-del-cafe-para-la-salud\/#primaryimage"},"image":{"@id":"https:\/\/www.baque.com\/es\/blog\/beneficios-del-cafe-para-la-salud\/#primaryimage"},"thumbnailUrl":"https:\/\/www.baque.com\/wp-content\/uploads\/2016\/10\/beneficios-del-cafe-para-la-salud.jpg","datePublished":"2016-10-04T09:03:32+00:00","dateModified":"2018-03-21T12:48:01+00:00","author":{"@id":"https:\/\/www.baque.com\/es\/#\/schema\/person\/32c8c583e6573818274e39ba0178ea0c"},"description":"Conoce algunos de los beneficios que aporta el caf\u00e9 al cuerpo humano. Ayuda a prevenir enfermedades y es fuente de energ\u00eda.","breadcrumb":{"@id":"https:\/\/www.baque.com\/es\/blog\/beneficios-del-cafe-para-la-salud\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.baque.com\/es\/blog\/beneficios-del-cafe-para-la-salud\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.baque.com\/es\/blog\/beneficios-del-cafe-para-la-salud\/#primaryimage","url":"https:\/\/www.baque.com\/wp-content\/uploads\/2016\/10\/beneficios-del-cafe-para-la-salud.jpg","contentUrl":"https:\/\/www.baque.com\/wp-content\/uploads\/2016\/10\/beneficios-del-cafe-para-la-salud.jpg","width":1300,"height":655},{"@type":"BreadcrumbList","@id":"https:\/\/www.baque.com\/es\/blog\/beneficios-del-cafe-para-la-salud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.baque.com\/es\/"},{"@type":"ListItem","position":2,"name":"Beneficios del caf\u00e9 para la salud"}]},{"@type":"WebSite","@id":"https:\/\/www.baque.com\/es\/#website","url":"https:\/\/www.baque.com\/es\/","name":"Caf\u00e9s Baqu\u00e9","description":"Somos l\u00edderes en hosteler\u00eda en Pa\u00eds Vasco y La Rioja y una de las marcas m\u00e1s reconocidas en el mercado nacional. Somos una empresa familiar en constante innovaci\u00f3n en el producto. Tostamos y distribuimos caf\u00e9 molido, en grano y c\u00e1psulas para disfrutar en casa, en el bar y en la oficina.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.baque.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.baque.com\/es\/#\/schema\/person\/32c8c583e6573818274e39ba0178ea0c","name":"baque","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e662fd223ca8a44ab1e60e541b95b68e1a42729b8396361e1232af01ddb23e51?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e662fd223ca8a44ab1e60e541b95b68e1a42729b8396361e1232af01ddb23e51?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e662fd223ca8a44ab1e60e541b95b68e1a42729b8396361e1232af01ddb23e51?s=96&d=mm&r=g","caption":"baque"}}]}},"_links":{"self":[{"href":"https:\/\/www.baque.com\/es\/wp-json\/wp\/v2\/posts\/2099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.baque.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.baque.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.baque.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.baque.com\/es\/wp-json\/wp\/v2\/comments?post=2099"}],"version-history":[{"count":0,"href":"https:\/\/www.baque.com\/es\/wp-json\/wp\/v2\/posts\/2099\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.baque.com\/es\/wp-json\/wp\/v2\/media\/2428"}],"wp:attachment":[{"href":"https:\/\/www.baque.com\/es\/wp-json\/wp\/v2\/media?parent=2099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.baque.com\/es\/wp-json\/wp\/v2\/categories?post=2099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.baque.com\/es\/wp-json\/wp\/v2\/tags?post=2099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}