
{"id":6093,"date":"2019-02-05T08:31:28","date_gmt":"2019-02-05T06:31:28","guid":{"rendered":"https:\/\/www.baque.com\/?p=6093"},"modified":"2019-04-08T15:07:56","modified_gmt":"2019-04-08T13:07:56","slug":"como-hacer-compost-casa","status":"publish","type":"post","link":"https:\/\/www.baque.com\/es\/blog\/como-hacer-compost-casa\/","title":{"rendered":"C\u00f3mo hacer compost en casa, los tips que necesitas"},"content":{"rendered":"<p class='entradilla'>Si quieres saber c\u00f3mo hacer compost en casa para tener abono para tu huerto o jard\u00edn no puedes perderte este art\u00edculo. Te lo contamos todo paso a paso.<\/p>\n<p>Despu\u00e9s de nuestro \u00faltimo lanzamiento, las <a href=\"https:\/\/www.capsulascompostables.es\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>c\u00e1psulas compostables de caf\u00e9<\/strong><\/a>, y dada la buen acogida que han tenido, hemos cre\u00eddo que tal vez os interesa saber <strong>c\u00f3mo hacer compost en casa,<\/strong> y as\u00ed poder reutilizarlo como abono para vuestra huerta o jard\u00edn.<\/p>\n<p>De este modo, no solamente ahorrar\u00e9is, sino que adem\u00e1s le dar\u00e9is una segunda vida a aquella materia org\u00e1nica que probablemente ibais a desechar.<\/p>\n<h2>C\u00f3mo hacer compost en casa, paso a paso<\/h2>\n<p>Una de las primeras cosas que debemos tener claras <a href=\"https:\/\/cocinillas.elespanol.com\/2017\/06\/hacer-compost-en-casa\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>antes de empezar a hacer compost en casa<\/strong><\/a> son las <a href=\"https:\/\/www.baque.com\/es\/blog\/diferencia-entre-biodegradable-y-compostable\/\"><strong>diferencias entre biodegradable y compostable<\/strong><\/a>. No vaya a ser que estemos haciendo compost con materia que no sea compostable, sino biodegradable y no consigamos que la mezcla fermente.<\/p>\n<ol>\n<li><strong>Busca el lugar adecuado donde hacer compost <\/strong>(un lugar recogido y c\u00e1lido), a poder ser a medio camino entre el huerto o jard\u00edn y la cocina, ese rinc\u00f3n de la casa donde m\u00e1s materia org\u00e1nica desechamos.<\/li>\n<li>Una vez sepas d\u00f3nde vas a hacerlo conviene que elijas entre un<strong> envase compostador o compostaje en mont\u00f3n<\/strong>.<\/li>\n<li><strong>Prepara la base<\/strong> con esti\u00e9rcol y una capa seca y le\u00f1osa.<\/li>\n<li>La segunda capa debe ser de <strong>materia org\u00e1nica<\/strong>. Procura ir alternando materia seca con materia h\u00fameda.<\/li>\n<li>Despu\u00e9s arroja de nuevo esti\u00e9rcol o una capa de compost viejo que utilizaremos como <strong>levadura<\/strong>.<\/li>\n<li><strong>Mezcla bien todos los materiales<\/strong> removi\u00e9ndolos.<\/li>\n<li>Cuando notes la mezcla seca <strong>ri\u00e9gala<\/strong>.<\/li>\n<li><strong>Contin\u00faa alternando<\/strong> capas y mezclando la materia.<\/li>\n<li>Habr\u00e1 que <strong>esperar de 4 a 5 meses<\/strong> para utilizar la parte inferior como compost.<\/li>\n<\/ol>\n<p>Recuerda que nuestras c\u00e1psulas compostables desaparecen en 3 meses si las desechas en el contenedor de materia org\u00e1nica (contenedor marr\u00f3n), uno de muchos <a href=\"https:\/\/www.baque.com\/es\/blog\/donde-desechar-producto-aprender-reciclar\/\"><strong>tipos de contenedores<\/strong><\/a>\u00a0con los que hoy contamos para reciclar y cuidar el medio ambiente.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5680\" src=\"https:\/\/www.baque.com\/wp-content\/uploads\/2018\/12\/baque-compostables-blog.jpg\" alt=\"C\u00e1psulas compostables CTA\" width=\"1150\" height=\"350\" srcset=\"https:\/\/www.baque.com\/wp-content\/uploads\/2018\/12\/baque-compostables-blog.jpg 1150w, https:\/\/www.baque.com\/wp-content\/uploads\/2018\/12\/baque-compostables-blog-331x101.jpg 331w, https:\/\/www.baque.com\/wp-content\/uploads\/2018\/12\/baque-compostables-blog-768x234.jpg 768w, https:\/\/www.baque.com\/wp-content\/uploads\/2018\/12\/baque-compostables-blog-600x183.jpg 600w\" sizes=\"auto, (max-width: 1150px) 100vw, 1150px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de nuestro \u00faltimo lanzamiento, las c\u00e1psulas compostables de caf\u00e9, y dada la buen acogida que han tenido, hemos cre\u00eddo que tal vez os interesa saber c\u00f3mo hacer compost en casa, y as\u00ed poder reutilizarlo como abono para vuestra huerta o jard\u00edn. De este modo, no solamente ahorrar\u00e9is, sino que adem\u00e1s le dar\u00e9is una segunda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6094,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[34],"tags":[16,50,382],"class_list":["post-6093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nos-gusta-el-cafe","tag-cafe-en-casa","tag-capsulas-compostables","tag-ecofriendly"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo hacer compost en casa, los tips que necesitas - Caf\u00e9s Baqu\u00e9<\/title>\n<meta name=\"description\" content=\"Si quieres saber c\u00f3mo hacer compost en casa para tener abono para tu huerto o jard\u00edn no puedes perderte este art\u00edculo. Te lo contamos todo paso a paso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo hacer compost en casa, los tips que necesitas - Caf\u00e9s Baqu\u00e9\" \/>\n<meta property=\"og:description\" content=\"Si quieres saber c\u00f3mo hacer compost en casa para tener abono para tu huerto o jard\u00edn no puedes perderte este art\u00edculo. Te lo contamos todo paso a paso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.baque.com\/es\/blog\/como-hacer-compost-casa\/\" \/>\n<meta property=\"og:site_name\" content=\"Caf\u00e9s Baqu\u00e9\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-05T06:31:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-08T13:07:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.baque.com\/wp-content\/uploads\/2019\/01\/como-hacer-compost-en-casa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"655\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"baque\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"baque\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/como-hacer-compost-casa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/como-hacer-compost-casa\\\/\"},\"author\":{\"name\":\"baque\",\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/#\\\/schema\\\/person\\\/32c8c583e6573818274e39ba0178ea0c\"},\"headline\":\"C\u00f3mo hacer compost en casa, los tips que necesitas\",\"datePublished\":\"2019-02-05T06:31:28+00:00\",\"dateModified\":\"2019-04-08T13:07:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/como-hacer-compost-casa\\\/\"},\"wordCount\":357,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/como-hacer-compost-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.baque.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/como-hacer-compost-en-casa.jpg\",\"keywords\":[\"caf\u00e9 en casa\",\"c\u00e1psulas compostables\",\"ecofriendly\"],\"articleSection\":[\"Nos gusta el caf\u00e9\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/como-hacer-compost-casa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/como-hacer-compost-casa\\\/\",\"url\":\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/como-hacer-compost-casa\\\/\",\"name\":\"C\u00f3mo hacer compost en casa, los tips que necesitas - Caf\u00e9s Baqu\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/como-hacer-compost-casa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/como-hacer-compost-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.baque.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/como-hacer-compost-en-casa.jpg\",\"datePublished\":\"2019-02-05T06:31:28+00:00\",\"dateModified\":\"2019-04-08T13:07:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/#\\\/schema\\\/person\\\/32c8c583e6573818274e39ba0178ea0c\"},\"description\":\"Si quieres saber c\u00f3mo hacer compost en casa para tener abono para tu huerto o jard\u00edn no puedes perderte este art\u00edculo. Te lo contamos todo paso a paso.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/como-hacer-compost-casa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/como-hacer-compost-casa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/como-hacer-compost-casa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.baque.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/como-hacer-compost-en-casa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.baque.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/como-hacer-compost-en-casa.jpg\",\"width\":1300,\"height\":655,\"caption\":\"c\u00f3mo hacer compost en casa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/blog\\\/como-hacer-compost-casa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.baque.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo hacer compost en casa, los tips que necesitas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.baque.com\\\/es\\\/\",\"name\":\"Caf\u00e9s Baqu\u00e9\",\"description\":\"Somos l\u00edderes en hosteler\u00eda en Pa\u00eds Vasco y La Rioja y una de las marcas m\u00e1s reconocidas en el mercado nacional. Somos una empresa familiar en constante innovaci\u00f3n en el producto. Tostamos y distribuimos caf\u00e9 molido, en grano y c\u00e1psulas para disfrutar en casa, en el bar y en la oficina.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.baque.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.baque.com\\\/es\\\/#\\\/schema\\\/person\\\/32c8c583e6573818274e39ba0178ea0c\",\"name\":\"baque\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e662fd223ca8a44ab1e60e541b95b68e1a42729b8396361e1232af01ddb23e51?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e662fd223ca8a44ab1e60e541b95b68e1a42729b8396361e1232af01ddb23e51?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e662fd223ca8a44ab1e60e541b95b68e1a42729b8396361e1232af01ddb23e51?s=96&d=mm&r=g\",\"caption\":\"baque\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo hacer compost en casa, los tips que necesitas - Caf\u00e9s Baqu\u00e9","description":"Si quieres saber c\u00f3mo hacer compost en casa para tener abono para tu huerto o jard\u00edn no puedes perderte este art\u00edculo. Te lo contamos todo paso a paso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo hacer compost en casa, los tips que necesitas - Caf\u00e9s Baqu\u00e9","og_description":"Si quieres saber c\u00f3mo hacer compost en casa para tener abono para tu huerto o jard\u00edn no puedes perderte este art\u00edculo. Te lo contamos todo paso a paso.","og_url":"https:\/\/www.baque.com\/es\/blog\/como-hacer-compost-casa\/","og_site_name":"Caf\u00e9s Baqu\u00e9","article_published_time":"2019-02-05T06:31:28+00:00","article_modified_time":"2019-04-08T13:07:56+00:00","og_image":[{"width":1300,"height":655,"url":"https:\/\/www.baque.com\/wp-content\/uploads\/2019\/01\/como-hacer-compost-en-casa.jpg","type":"image\/jpeg"}],"author":"baque","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"baque","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.baque.com\/es\/blog\/como-hacer-compost-casa\/#article","isPartOf":{"@id":"https:\/\/www.baque.com\/es\/blog\/como-hacer-compost-casa\/"},"author":{"name":"baque","@id":"https:\/\/www.baque.com\/es\/#\/schema\/person\/32c8c583e6573818274e39ba0178ea0c"},"headline":"C\u00f3mo hacer compost en casa, los tips que necesitas","datePublished":"2019-02-05T06:31:28+00:00","dateModified":"2019-04-08T13:07:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.baque.com\/es\/blog\/como-hacer-compost-casa\/"},"wordCount":357,"commentCount":0,"image":{"@id":"https:\/\/www.baque.com\/es\/blog\/como-hacer-compost-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.baque.com\/wp-content\/uploads\/2019\/01\/como-hacer-compost-en-casa.jpg","keywords":["caf\u00e9 en casa","c\u00e1psulas compostables","ecofriendly"],"articleSection":["Nos gusta el caf\u00e9"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.baque.com\/es\/blog\/como-hacer-compost-casa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.baque.com\/es\/blog\/como-hacer-compost-casa\/","url":"https:\/\/www.baque.com\/es\/blog\/como-hacer-compost-casa\/","name":"C\u00f3mo hacer compost en casa, los tips que necesitas - Caf\u00e9s Baqu\u00e9","isPartOf":{"@id":"https:\/\/www.baque.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.baque.com\/es\/blog\/como-hacer-compost-casa\/#primaryimage"},"image":{"@id":"https:\/\/www.baque.com\/es\/blog\/como-hacer-compost-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.baque.com\/wp-content\/uploads\/2019\/01\/como-hacer-compost-en-casa.jpg","datePublished":"2019-02-05T06:31:28+00:00","dateModified":"2019-04-08T13:07:56+00:00","author":{"@id":"https:\/\/www.baque.com\/es\/#\/schema\/person\/32c8c583e6573818274e39ba0178ea0c"},"description":"Si quieres saber c\u00f3mo hacer compost en casa para tener abono para tu huerto o jard\u00edn no puedes perderte este art\u00edculo. Te lo contamos todo paso a paso.","breadcrumb":{"@id":"https:\/\/www.baque.com\/es\/blog\/como-hacer-compost-casa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.baque.com\/es\/blog\/como-hacer-compost-casa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.baque.com\/es\/blog\/como-hacer-compost-casa\/#primaryimage","url":"https:\/\/www.baque.com\/wp-content\/uploads\/2019\/01\/como-hacer-compost-en-casa.jpg","contentUrl":"https:\/\/www.baque.com\/wp-content\/uploads\/2019\/01\/como-hacer-compost-en-casa.jpg","width":1300,"height":655,"caption":"c\u00f3mo hacer compost en casa"},{"@type":"BreadcrumbList","@id":"https:\/\/www.baque.com\/es\/blog\/como-hacer-compost-casa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.baque.com\/es\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo hacer compost en casa, los tips que necesitas"}]},{"@type":"WebSite","@id":"https:\/\/www.baque.com\/es\/#website","url":"https:\/\/www.baque.com\/es\/","name":"Caf\u00e9s Baqu\u00e9","description":"Somos l\u00edderes en hosteler\u00eda en Pa\u00eds Vasco y La Rioja y una de las marcas m\u00e1s reconocidas en el mercado nacional. Somos una empresa familiar en constante innovaci\u00f3n en el producto. Tostamos y distribuimos caf\u00e9 molido, en grano y c\u00e1psulas para disfrutar en casa, en el bar y en la oficina.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.baque.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.baque.com\/es\/#\/schema\/person\/32c8c583e6573818274e39ba0178ea0c","name":"baque","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e662fd223ca8a44ab1e60e541b95b68e1a42729b8396361e1232af01ddb23e51?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e662fd223ca8a44ab1e60e541b95b68e1a42729b8396361e1232af01ddb23e51?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e662fd223ca8a44ab1e60e541b95b68e1a42729b8396361e1232af01ddb23e51?s=96&d=mm&r=g","caption":"baque"}}]}},"_links":{"self":[{"href":"https:\/\/www.baque.com\/es\/wp-json\/wp\/v2\/posts\/6093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.baque.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.baque.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.baque.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.baque.com\/es\/wp-json\/wp\/v2\/comments?post=6093"}],"version-history":[{"count":5,"href":"https:\/\/www.baque.com\/es\/wp-json\/wp\/v2\/posts\/6093\/revisions"}],"predecessor-version":[{"id":6765,"href":"https:\/\/www.baque.com\/es\/wp-json\/wp\/v2\/posts\/6093\/revisions\/6765"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.baque.com\/es\/wp-json\/wp\/v2\/media\/6094"}],"wp:attachment":[{"href":"https:\/\/www.baque.com\/es\/wp-json\/wp\/v2\/media?parent=6093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.baque.com\/es\/wp-json\/wp\/v2\/categories?post=6093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.baque.com\/es\/wp-json\/wp\/v2\/tags?post=6093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}